{"id":28991,"date":"2020-07-29T01:10:48","date_gmt":"2020-07-29T04:10:48","guid":{"rendered":"https:\/\/www.dientedelecheart.com\/web2022\/productos\/import-placeholder-for-5251\/"},"modified":"2020-07-29T01:10:56","modified_gmt":"2020-07-29T04:10:56","slug":"sellos-de-goma-127","status":"publish","type":"product","link":"https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/","title":{"rendered":"Sellos de Goma"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":7856,"template":"","meta":[],"product_brand":[],"product_cat":[704],"product_tag":[],"class_list":["post-28991","product","type-product","status-publish","has-post-thumbnail","product_cat-sellos-de-goma","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-after_add_to_cart"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.2 (Yoast SEO v25.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sellos de Goma - Diente de Leche Art<\/title>\n<meta name=\"description\" content=\"Sellos de Goma - Diente de Leche Art\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sellos de Goma\" \/>\n<meta property=\"og:description\" content=\"Sellos de Goma - Diente de Leche Art\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/\" \/>\n<meta property=\"og:site_name\" content=\"Diente de Leche Art\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-29T04:10:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/dientedelecheart.com\/web2022\/wp-content\/uploads\/2020\/Productos\/SN_3\/P1060144.JPG?fit=864%2C1152&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"864\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/\",\"url\":\"https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/\",\"name\":\"Sellos de Goma - Diente de Leche Art\",\"isPartOf\":{\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/dientedelecheart.com\/web2022\/wp-content\/uploads\/2020\/Productos\/SN_3\/P1060144.JPG?fit=864%2C1152&ssl=1\",\"datePublished\":\"2020-07-29T04:10:48+00:00\",\"dateModified\":\"2020-07-29T04:10:56+00:00\",\"description\":\"Sellos de Goma - Diente de Leche Art\",\"breadcrumb\":{\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/#breadcrumb\"},\"inLanguage\":\"es-UY\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-UY\",\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/dientedelecheart.com\/web2022\/wp-content\/uploads\/2020\/Productos\/SN_3\/P1060144.JPG?fit=864%2C1152&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/dientedelecheart.com\/web2022\/wp-content\/uploads\/2020\/Productos\/SN_3\/P1060144.JPG?fit=864%2C1152&ssl=1\",\"width\":864,\"height\":1152},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dientedelecheart.com\/web2022\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\/\/dientedelecheart.com\/web2022\/?page_id=81891\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sellos de Goma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/#website\",\"url\":\"https:\/\/dientedelecheart.com\/web2022\/\",\"name\":\"Diente de Leche Art\",\"description\":\"Diente de Leche Art\",\"publisher\":{\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dientedelecheart.com\/web2022\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-UY\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/#organization\",\"name\":\"Diente de Leche Art\",\"url\":\"https:\/\/dientedelecheart.com\/web2022\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-UY\",\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/www.dientedelecheart.com\/web2022\/wp-content\/uploads\/2022\/04\/icono.png?fit=72%2C72&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.dientedelecheart.com\/web2022\/wp-content\/uploads\/2022\/04\/icono.png?fit=72%2C72&ssl=1\",\"width\":72,\"height\":72,\"caption\":\"Diente de Leche Art\"},\"image\":{\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/dientedelecheart\/\"],\"email\":\"infodientedelecheart@gmail.com\",\"telephone\":\"+598 94 303 921\",\"legalName\":\"Diente de Leche Art\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sellos de Goma - Diente de Leche Art","description":"Sellos de Goma - Diente de Leche Art","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/","og_locale":"es_ES","og_type":"article","og_title":"Sellos de Goma","og_description":"Sellos de Goma - Diente de Leche Art","og_url":"https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/","og_site_name":"Diente de Leche Art","article_modified_time":"2020-07-29T04:10:56+00:00","og_image":[{"width":864,"height":1152,"url":"https:\/\/i0.wp.com\/dientedelecheart.com\/web2022\/wp-content\/uploads\/2020\/Productos\/SN_3\/P1060144.JPG?fit=864%2C1152&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/","url":"https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/","name":"Sellos de Goma - Diente de Leche Art","isPartOf":{"@id":"https:\/\/dientedelecheart.com\/web2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/#primaryimage"},"image":{"@id":"https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/dientedelecheart.com\/web2022\/wp-content\/uploads\/2020\/Productos\/SN_3\/P1060144.JPG?fit=864%2C1152&ssl=1","datePublished":"2020-07-29T04:10:48+00:00","dateModified":"2020-07-29T04:10:56+00:00","description":"Sellos de Goma - Diente de Leche Art","breadcrumb":{"@id":"https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/#breadcrumb"},"inLanguage":"es-UY","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/"]}]},{"@type":"ImageObject","inLanguage":"es-UY","@id":"https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/#primaryimage","url":"https:\/\/i0.wp.com\/dientedelecheart.com\/web2022\/wp-content\/uploads\/2020\/Productos\/SN_3\/P1060144.JPG?fit=864%2C1152&ssl=1","contentUrl":"https:\/\/i0.wp.com\/dientedelecheart.com\/web2022\/wp-content\/uploads\/2020\/Productos\/SN_3\/P1060144.JPG?fit=864%2C1152&ssl=1","width":864,"height":1152},{"@type":"BreadcrumbList","@id":"https:\/\/dientedelecheart.com\/web2022\/productos\/sellos\/sellos-de-goma\/sellos-de-goma-127\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dientedelecheart.com\/web2022\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/dientedelecheart.com\/web2022\/?page_id=81891"},{"@type":"ListItem","position":3,"name":"Sellos de Goma"}]},{"@type":"WebSite","@id":"https:\/\/dientedelecheart.com\/web2022\/#website","url":"https:\/\/dientedelecheart.com\/web2022\/","name":"Diente de Leche Art","description":"Diente de Leche Art","publisher":{"@id":"https:\/\/dientedelecheart.com\/web2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dientedelecheart.com\/web2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-UY"},{"@type":"Organization","@id":"https:\/\/dientedelecheart.com\/web2022\/#organization","name":"Diente de Leche Art","url":"https:\/\/dientedelecheart.com\/web2022\/","logo":{"@type":"ImageObject","inLanguage":"es-UY","@id":"https:\/\/dientedelecheart.com\/web2022\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.dientedelecheart.com\/web2022\/wp-content\/uploads\/2022\/04\/icono.png?fit=72%2C72&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.dientedelecheart.com\/web2022\/wp-content\/uploads\/2022\/04\/icono.png?fit=72%2C72&ssl=1","width":72,"height":72,"caption":"Diente de Leche Art"},"image":{"@id":"https:\/\/dientedelecheart.com\/web2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/dientedelecheart\/"],"email":"infodientedelecheart@gmail.com","telephone":"+598 94 303 921","legalName":"Diente de Leche Art"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/dientedelecheart.com\/web2022\/wp-json\/wp\/v2\/product\/28991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dientedelecheart.com\/web2022\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dientedelecheart.com\/web2022\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dientedelecheart.com\/web2022\/wp-json\/wp\/v2\/media\/7856"}],"wp:attachment":[{"href":"https:\/\/dientedelecheart.com\/web2022\/wp-json\/wp\/v2\/media?parent=28991"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dientedelecheart.com\/web2022\/wp-json\/wp\/v2\/product_brand?post=28991"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dientedelecheart.com\/web2022\/wp-json\/wp\/v2\/product_cat?post=28991"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dientedelecheart.com\/web2022\/wp-json\/wp\/v2\/product_tag?post=28991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}