{"id":30309,"date":"2020-07-29T01:37:04","date_gmt":"2020-07-29T04:37:04","guid":{"rendered":"https:\/\/www.dientedelecheart.com\/web2022\/productos\/import-placeholder-for-6567\/"},"modified":"2020-07-29T01:37:14","modified_gmt":"2020-07-29T04:37:14","slug":"kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126","status":"publish","type":"product","link":"https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/","title":{"rendered":"Kit de Servilletas 33&#215;33 cm (2 modelos, 10 de c\/u)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Ideal para trabajos de decoupage. Las im\u00e1genes se refieren a una de las cuatro caras y puede existir variaci\u00f3n del dise\u00f1o en los otros lados.<\/p>\n","protected":false},"featured_media":11693,"template":"","meta":[],"product_brand":[],"product_cat":[716],"product_tag":[],"class_list":["post-30309","product","type-product","status-publish","has-post-thumbnail","product_cat-kit-servilletas","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-after_add_to_cart"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.2 (Yoast SEO v25.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kit de Servilletas 33x33 cm (2 modelos, 10 de c\/u) - Diente de Leche Art<\/title>\n<meta name=\"description\" content=\"Kit de Servilletas 33x33 cm (2 modelos, 10 de c\/u) - Diente de Leche Art\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kit de Servilletas 33x33 cm (2 modelos, 10 de c\/u)\" \/>\n<meta property=\"og:description\" content=\"Kit de Servilletas 33x33 cm (2 modelos, 10 de c\/u) - Diente de Leche Art\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/\" \/>\n<meta property=\"og:site_name\" content=\"Diente de Leche Art\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-29T04:37:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/dientedelecheart.com\/web2022\/wp-content\/uploads\/2020\/Productos\/SN_11\/P1100411.JPG?fit=864%2C1152&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"864\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/\",\"url\":\"https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/\",\"name\":\"Kit de Servilletas 33x33 cm (2 modelos, 10 de c\/u) - Diente de Leche Art\",\"isPartOf\":{\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/dientedelecheart.com\/web2022\/wp-content\/uploads\/2020\/Productos\/SN_11\/P1100411.JPG?fit=864%2C1152&ssl=1\",\"datePublished\":\"2020-07-29T04:37:04+00:00\",\"dateModified\":\"2020-07-29T04:37:14+00:00\",\"description\":\"Kit de Servilletas 33x33 cm (2 modelos, 10 de c\/u) - Diente de Leche Art\",\"breadcrumb\":{\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/#breadcrumb\"},\"inLanguage\":\"es-UY\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-UY\",\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/dientedelecheart.com\/web2022\/wp-content\/uploads\/2020\/Productos\/SN_11\/P1100411.JPG?fit=864%2C1152&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/dientedelecheart.com\/web2022\/wp-content\/uploads\/2020\/Productos\/SN_11\/P1100411.JPG?fit=864%2C1152&ssl=1\",\"width\":864,\"height\":1152},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dientedelecheart.com\/web2022\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\/\/dientedelecheart.com\/web2022\/?page_id=81891\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kit de Servilletas 33&#215;33 cm (2 modelos, 10 de c\/u)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/#website\",\"url\":\"https:\/\/dientedelecheart.com\/web2022\/\",\"name\":\"Diente de Leche Art\",\"description\":\"Diente de Leche Art\",\"publisher\":{\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dientedelecheart.com\/web2022\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-UY\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/#organization\",\"name\":\"Diente de Leche Art\",\"url\":\"https:\/\/dientedelecheart.com\/web2022\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-UY\",\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/www.dientedelecheart.com\/web2022\/wp-content\/uploads\/2022\/04\/icono.png?fit=72%2C72&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.dientedelecheart.com\/web2022\/wp-content\/uploads\/2022\/04\/icono.png?fit=72%2C72&ssl=1\",\"width\":72,\"height\":72,\"caption\":\"Diente de Leche Art\"},\"image\":{\"@id\":\"https:\/\/dientedelecheart.com\/web2022\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/dientedelecheart\/\"],\"email\":\"infodientedelecheart@gmail.com\",\"telephone\":\"+598 94 303 921\",\"legalName\":\"Diente de Leche Art\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kit de Servilletas 33x33 cm (2 modelos, 10 de c\/u) - Diente de Leche Art","description":"Kit de Servilletas 33x33 cm (2 modelos, 10 de c\/u) - Diente de Leche Art","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/","og_locale":"es_ES","og_type":"article","og_title":"Kit de Servilletas 33x33 cm (2 modelos, 10 de c\/u)","og_description":"Kit de Servilletas 33x33 cm (2 modelos, 10 de c\/u) - Diente de Leche Art","og_url":"https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/","og_site_name":"Diente de Leche Art","article_modified_time":"2020-07-29T04:37:14+00:00","og_image":[{"width":864,"height":1152,"url":"https:\/\/i0.wp.com\/dientedelecheart.com\/web2022\/wp-content\/uploads\/2020\/Productos\/SN_11\/P1100411.JPG?fit=864%2C1152&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/","url":"https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/","name":"Kit de Servilletas 33x33 cm (2 modelos, 10 de c\/u) - Diente de Leche Art","isPartOf":{"@id":"https:\/\/dientedelecheart.com\/web2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/#primaryimage"},"image":{"@id":"https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/dientedelecheart.com\/web2022\/wp-content\/uploads\/2020\/Productos\/SN_11\/P1100411.JPG?fit=864%2C1152&ssl=1","datePublished":"2020-07-29T04:37:04+00:00","dateModified":"2020-07-29T04:37:14+00:00","description":"Kit de Servilletas 33x33 cm (2 modelos, 10 de c\/u) - Diente de Leche Art","breadcrumb":{"@id":"https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/#breadcrumb"},"inLanguage":"es-UY","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/"]}]},{"@type":"ImageObject","inLanguage":"es-UY","@id":"https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/#primaryimage","url":"https:\/\/i0.wp.com\/dientedelecheart.com\/web2022\/wp-content\/uploads\/2020\/Productos\/SN_11\/P1100411.JPG?fit=864%2C1152&ssl=1","contentUrl":"https:\/\/i0.wp.com\/dientedelecheart.com\/web2022\/wp-content\/uploads\/2020\/Productos\/SN_11\/P1100411.JPG?fit=864%2C1152&ssl=1","width":864,"height":1152},{"@type":"BreadcrumbList","@id":"https:\/\/dientedelecheart.com\/web2022\/productos\/servilletas\/kit-servilletas\/kit-de-servilletas-33x33-cm-2-modelos-10-de-c-u-126\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dientedelecheart.com\/web2022\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/dientedelecheart.com\/web2022\/?page_id=81891"},{"@type":"ListItem","position":3,"name":"Kit de Servilletas 33&#215;33 cm (2 modelos, 10 de c\/u)"}]},{"@type":"WebSite","@id":"https:\/\/dientedelecheart.com\/web2022\/#website","url":"https:\/\/dientedelecheart.com\/web2022\/","name":"Diente de Leche Art","description":"Diente de Leche Art","publisher":{"@id":"https:\/\/dientedelecheart.com\/web2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dientedelecheart.com\/web2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-UY"},{"@type":"Organization","@id":"https:\/\/dientedelecheart.com\/web2022\/#organization","name":"Diente de Leche Art","url":"https:\/\/dientedelecheart.com\/web2022\/","logo":{"@type":"ImageObject","inLanguage":"es-UY","@id":"https:\/\/dientedelecheart.com\/web2022\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.dientedelecheart.com\/web2022\/wp-content\/uploads\/2022\/04\/icono.png?fit=72%2C72&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.dientedelecheart.com\/web2022\/wp-content\/uploads\/2022\/04\/icono.png?fit=72%2C72&ssl=1","width":72,"height":72,"caption":"Diente de Leche Art"},"image":{"@id":"https:\/\/dientedelecheart.com\/web2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/dientedelecheart\/"],"email":"infodientedelecheart@gmail.com","telephone":"+598 94 303 921","legalName":"Diente de Leche Art"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/dientedelecheart.com\/web2022\/wp-json\/wp\/v2\/product\/30309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dientedelecheart.com\/web2022\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dientedelecheart.com\/web2022\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dientedelecheart.com\/web2022\/wp-json\/wp\/v2\/media\/11693"}],"wp:attachment":[{"href":"https:\/\/dientedelecheart.com\/web2022\/wp-json\/wp\/v2\/media?parent=30309"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dientedelecheart.com\/web2022\/wp-json\/wp\/v2\/product_brand?post=30309"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dientedelecheart.com\/web2022\/wp-json\/wp\/v2\/product_cat?post=30309"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dientedelecheart.com\/web2022\/wp-json\/wp\/v2\/product_tag?post=30309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}